{"id":97,"date":"2017-01-12T19:39:30","date_gmt":"2017-01-12T18:39:30","guid":{"rendered":"http:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/?p=97"},"modified":"2017-01-12T11:47:31","modified_gmt":"2017-01-12T10:47:31","slug":"seduti-al-tavolino","status":"publish","type":"post","link":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/senza-categoria\/seduti-al-tavolino\/","title":{"rendered":"Seduti al tavolino"},"content":{"rendered":"<p><strong>di Giannantonio Spotorno<\/strong><\/p>\n<p><span class=\"messagebody2\"><span style=\"font-size: large;\">La conoscenza \u201cin breve\u201d non rende competenti; in futuro sar\u00e0 diverso, ma oggi non \u00e8 <\/span> <\/span><span style=\"font-size: large;\"><span class=\"messagebody\"> ancora possibile infilarla nella testa della gente come si fa con i file nei computer.<\/span> <\/span><span class=\"messagebody\"> <span style=\"font-size: large;\">La semplicit\u00e0 rende bella l&#8217;anima ma non arricchisce la conoscenza n\u00e9 l\u2019esperienza; insomma, la vita pu\u00f2 anche essere affrontata in modo semplice, ma ci\u00f2 non toglie che essa chieda di capire cose complesse \u2026 poi, se si confonde la semplicit\u00e0 con la superficialit\u00e0, allora sono guai.<\/span><\/span><\/p>\n<p><span class=\"messagebody\"> <span style=\"font-size: large;\">I ventidue capitoli fin qui scritti, costituiscono una sorta di base per inoltrarsi nei successivi argomenti del presente corso.<\/span><\/span><\/p>\n<p><span class=\"messagebody\"> <span style=\"font-size: large;\">Naturalmente, \u00e8 sempre fatta richiesta a presidenti, ministri, parlamentari, segretari, dirigenti e quanti altri, di segnalare ed eventualmente dimostrare che non sia pertinente al vero quanto qui si descrive, racconta e afferma.<\/span><\/span><\/p>\n<p><span style=\"font-size: large;\">A testimonianza di una democrazia spesso travisata, non esiste un solo statuto di partito che menzioni i pacchettari, i capicorrente e i tavolini che \u201cpilotano\u201d i congressi; ci sono anche altri \u201ccasi\u201d che gli accennati statuti non contemplano, ma prendiamo intanto atto di questi.<\/span><\/p>\n<p><span style=\"font-size: large;\">Le \u201cqualifiche\u201d per sedersi intorno al pi\u00f9 volte menzionato tavolino del preordino dei congressi, non sono tante ma senza esse a quel tavolino non ci si siede.<\/span><\/p>\n<p><span style=\"font-size: large;\">In breve, ciascuno dei convenuti dovr\u00e0 avere il controllo del suo bel pacchetto di tessere e conoscere bene ogni particolare dello schema delle tre linee parallele (Partito, Istituzione e Sottobosco), che abbiamo disegnato nei <b> <a href=\"http:\/\/www.opinione.it\/politica\/2015\/08\/01\/spotorno_politica-01-08.aspx\"> capitoli 1<\/a><\/b> e <b> <a href=\"http:\/\/www.opinione.it\/politica\/2015\/08\/08\/spotorno_politica-08-08.aspx\"> 2<\/a><\/b> di questo corso.<\/span><\/p>\n<p><span style=\"font-size: large;\">Il pacchetto di tessere serve per avere riconosciuta la corrispondente percentuale di controllo del partito; poi, la perizia nel districarsi tra la miriade di ruoli e cariche che le note tre linee rappresentano, permetter\u00e0 di trasformare detta percentuale in pari assegnazioni preventive tra posizioni nel partito, nelle istituzioni e nel sottobosco, sulle quali il convenuto al tavolino vorr\u00e0 \u201callungare le proprie mani\u201d.<\/span><\/p>\n<p><span style=\"font-size: large;\">Alla fine, il tavolino avr\u00e0 stabilito quali dirigenti del partito saranno rinnovati dal congresso e quali\u00a0 riconfermati come \u201ca vita\u201d; cos\u00ec come avr\u00e0 stabilito i nomi di chi \u201ccorrer\u00e0\u201d per le istituzioni parlamentari, in base all\u2019ovvia corrente di riferimento.<\/span><\/p>\n<p><span style=\"font-size: large;\">Inoltre, avr\u00e0 \u201cscelto\u201d dei dirigenti e anche dei funzionari di ruoli secondari relativi al \u201csottobosco\u201d, ovvero alle pubbliche amministrazioni periferiche e a tutte le attivit\u00e0 alle quali la mano pubblica pu\u00f2 in qualche modo porre condizioni.\u00a0 <\/span><\/p>\n<p><span style=\"font-size: large;\">Detto tavolino si riunisce anche nelle sedi di partito, ma sempre e rigorosamente a porte chiuse; le poche sedie intorno, sono riservate a \u201cprecisi\u201d parlamentari del collegio, al segretario, coordinatore o primo riferimento provinciale del partito e a pochissimi alti dirigenti istituzionali. Abbiamo intuito la funzione del tavolino e ne intuiremo altre, ma l\u00ec nessuno parla di ci\u00f2 che interessa al popolo.<\/span><\/p>\n<p><span style=\"font-size: large;\">Dalla povert\u00e0 al rosario delle vessazioni istituzionali, come dall\u2019ignominiosa burocrazia ad altre mille ingiustizie, sembra che di tutto ci\u00f2 a quel tavolo non gliene freghi nulla.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Giannantonio Spotorno La conoscenza \u201cin breve\u201d non rende competenti; in futuro sar\u00e0 diverso, ma oggi non \u00e8 ancora possibile infilarla nella testa della gente come si fa con i file nei computer. La semplicit\u00e0 rende bella l&#8217;anima ma non arricchisce la conoscenza n\u00e9 l\u2019esperienza; insomma, la vita pu\u00f2 anche essere affrontata in modo semplice, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":98,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-97","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-senza-categoria"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/posts\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/comments?post=97"}],"version-history":[{"count":1,"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/posts\/97\/revisions"}],"predecessor-version":[{"id":99,"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/posts\/97\/revisions\/99"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/media\/98"}],"wp:attachment":[{"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/media?parent=97"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/categories?post=97"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilcittadinoonline.it\/ti-racconto-la-politica\/wp-json\/wp\/v2\/tags?post=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}